{"id":11035,"date":"2021-08-18T22:41:18","date_gmt":"2021-08-18T22:41:18","guid":{"rendered":"https:\/\/nosotrasenlibertad.com\/libroweb\/?page_id=11035"},"modified":"2022-12-15T15:08:47","modified_gmt":"2022-12-15T15:08:47","slug":"2019-nos-reencontramos","status":"publish","type":"page","link":"https:\/\/nosotrasenlibertad.com\/libroweb\/2019-nos-reencontramos\/","title":{"rendered":"2019 Nos reencontramos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Cr\u00f3nica de un encuentro&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No fue un encuentro. Fueron miles de encuentros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sucedi\u00f3 ayer. No puedo escribir una cr\u00f3nica del encuentro. Solo puedo escribir la m\u00eda. Que es una entre las doscientas cincuenta que dicen que \u00e9ramos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi cr\u00f3nica empieza alrededor de la una del mediod\u00eda cuando llegu\u00e9 al lugar. Entr\u00e9 al Hotel y estaba a punto de acercarme a recepci\u00f3n para preguntar d\u00f3nde era, pero no fue necesario. El bullicio me fue guiando. En la puerta, una mujer que yo no conoc\u00eda me dio un sticker para que ponga mi nombre y me lo pegue en la ropa. Entr\u00e9, perdida. Vamos a ver, hab\u00eda m\u00e1s o menos cuarenta mesas redondas alrededor de las cuales estaban m\u00e1s o menos sentadas ocho mujeres en completo desorden. Hab\u00eda tambi\u00e9n, como yo, montones de mujeres caminando perdidas o encontradas entre las mesas. Hab\u00eda mujeres abraz\u00e1ndose mucho. Casi todas con el sticker pegado porque hab\u00edan pasado cuarenta a\u00f1os. Redondeando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda tambi\u00e9n alguien con un micr\u00f3fono y desde el peque\u00f1o escenario dec\u00eda algo as\u00ed como chicas, vayan sent\u00e1ndose que empieza el almuerzo. Yo, perdida como estaba, llena de bultos, cartera, tapado, paraguas, bolsita con libros, divis\u00e9 una cara conocida. Me acerqu\u00e9. Y a partir de ese momento, no par\u00e9. Como si todo hubiera estado a oscuras y de pronto alguien enciende una luz. Las vi a todas. Una por una. Las que se me acercaban y me abrazaban, sin siquiera mirar mi papelito pegado en la solapa. Las que yo me quedaba mirando porque una sonrisa me tra\u00eda otro rostro m\u00e1s joven, de all\u00e1 lejos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full mf\"><img decoding=\"async\" width=\"860\" height=\"575\" data-src=\"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/09\/bauen.jpg\" alt=\"\" class=\"wp-image-11557 lazyload\" data-srcset=\"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/09\/bauen.jpg 860w, https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/09\/bauen-768x513.jpg 768w\" data-sizes=\"(max-width: 860px) 100vw, 860px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 860px; --smush-placeholder-aspect-ratio: 860\/575;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized imgFloat\"><img decoding=\"async\" data-src=\"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/08\/reencuentro.jpg\" alt=\"\" class=\"wp-image-11044 lazyload\" width=\"400\" height=\"400\" data-srcset=\"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/08\/reencuentro.jpg 800w, https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/08\/reencuentro-768x768.jpg 768w\" data-sizes=\"(max-width: 400px) 100vw, 400px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como hab\u00eda que buscar un lugar, encontr\u00e9 uno en mi camino de abrazos. Pude dejar mis b\u00e1rtulos en la silla y descansar unos minutos, en una mesa donde estaba comiendo el hijo de una de las compa\u00f1eras. Me trajeron un plato de comida. \u00c9l me dijo que me recordaba. Ten\u00eda pocos a\u00f1os, ponele siete, cuando ven\u00eda de visita con su abuela a ver a su mam\u00e1 que estaba conmigo en el Pabell\u00f3n. Al rato, vinieron a presentarle a otro de los chicos de ese entonces. Los dos de casi cincuenta a\u00f1os \u00bfSe reconocieron? No lo s\u00e9 \u00bfQu\u00e9 miraban los ni\u00f1os cuando ven\u00edan a ver a sus madres presas? No lo s\u00e9. No lo s\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sigo deambulando por las mesas, busco. Busco ojos. Y encuentro, claro. Cada uno un abrazo. Mientras tanto desde el escenario anuncian cosas. Piden silencio pero nadie escucha. Pero pasan cosas. Habr\u00e1 quien lo cuente mejor que yo. Yo estaba tan distra\u00edda con los abrazos. Diamante. Santiago del Estero. Alguna cordobesa. Confundo nombres. Miro stickers pegados en los pechos de las chicas. Y luego abrazo. A veces, es al rev\u00e9s. Abrazo y despu\u00e9s miro, o pregunto \u00bfqui\u00e9n sos? En alg\u00fan momento, para m\u00ed el mejor momento, una de las chicas agarra guitarra y empieza a cantar. Su voz, la vuelve joven, a todas nos vuelve j\u00f3venes. Me doy cuenta que la m\u00fasica fue m\u00e1s importante que otras identificaciones pol\u00edticas. Al menos para m\u00ed. Pero bueno, al fin y al cabo, esta es mi cr\u00f3nica. Y habr\u00e1 muchas otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me voy cuando me doy cuenta que ya no puedo hablar. Igual ya falta poco para que termine el encuentro, son las seis y media de la tarde. En la puerta, me sigo encontrando con chicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llego a casa. Tengo muchas historias guardadas que me contaron. Tengo tambi\u00e9n n\u00fameros de tel\u00e9fono guardados. Tengo un tel\u00e9fono que anot\u00e9 y no se de quien es. No recuerdo. Bueno, da igual. La llamo y veo quien contesta del otro lado. Tengo. Tengo alegr\u00eda. Mucha. Hinchada de amor y gloria. As\u00ed he vuelto a casa hoy. Y te juro que no exagero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Patricia Borenstein<\/strong><br>Septiembre 2020<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns recuadroBlanco is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"nacimiento\"><strong>Nacimiento de Viuda y novias de Pappo<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized imgFloat\"><img decoding=\"async\" data-src=\"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/08\/viudas.jpg\" alt=\"\" class=\"wp-image-11051 lazyload\" width=\"430\" height=\"350\" data-srcset=\"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/08\/viudas.jpg 860w, https:\/\/nosotrasenlibertad.com\/libroweb\/wp-content\/uploads\/2021\/08\/viudas-768x625.jpg 768w\" data-sizes=\"(max-width: 430px) 100vw, 430px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 430px; --smush-placeholder-aspect-ratio: 430\/350;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Todo fue debatido como en los viejos tiempos, cada detalle fue puesto a la discusi\u00f3n del colectivo, la hora, el lugar, la comida, y por supuesto el encuentro \u00bfIr\u00edamos a abrazarnos al Obelisco como alguna vez so\u00f1amos hace cuarenta a\u00f1os atr\u00e1s?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue una ardua discusi\u00f3n. S\u00ed, no, \u00bfc\u00f3mo, porqu\u00e9, es necesario, es peligroso? Todas las preguntas posibles y sus respectivas respuestas aparecieron en el Nosotras, el wasap en esos tiempos estaba al rojo vivo\u2026pero la decisi\u00f3n final estuvo en manos de la querida naturaleza. Ese glorioso d\u00eda 15 de junio de 2019 cayeron sapos del cielo, de manera que cada quien lleg\u00f3 como pudo al hotel Buen y el abrazo al Obelisco qued\u00f3 en el recuerdo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda previo nos reunimos todas en el depto. de Silvita Asaro con anexo depto. Cristina Rebello todo en el mismo piso, solo peque\u00f1o palier de separaci\u00f3n y as\u00ed logramos el ensayo general antes de nuestra presentaci\u00f3n, entre risas, an\u00e9cdotas y ruedas de vino.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la ma\u00f1ana llov\u00eda a cantaros, salieron Pluta y Silvi en un taxi y las seguimos en otro, Panci Carlota, Panter y yo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apenas lo tomamos se da una charla con el taxista sobre el tiempo y seguidamente el tipo me mira. Yo iba en el asiento del acompa\u00f1ante con un piloto, mochila, una bolsa y el bombo de la Pluta\u2026hab\u00edan dicho: \u2013\u00a1No se olviden el bombo de la Pluta!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013\u00bfSon de un grupo folcl\u00f3rico?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo miro, giro y la veo a la Panci, con mirada c\u00f3mplice y con la carcajada a punto de brotar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013No, somos una banda de rock, V<em>iuda y novias de Pappo<\/em>. Y ella, es la viuda de Pappo, digo se\u00f1alando a la Panci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El tipo muestra curiosidad, extra\u00f1eza y quiz\u00e1s lo transportamos a alg\u00fan lejano recuerdo de recital. Voltea la cabeza para mirarla, quer\u00eda saber cu\u00e1l de esas mujeres era la viuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Enseguida le aclaro que es la viuda, pero clandestina, y que no cobr\u00f3 nada, no le dejo herencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas asintiendo y agregando alg\u00fan detalle a la historia, aguantando las carcajadas hasta que nos bajamos. La fiesta hab\u00eda empezado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La risa fue una de nuestras armas m\u00e1s poderosas de resistencia y por suerte no lo hab\u00edamos olvidado. Atravesamos la puerta del Bauen, felices, riendo y con el bombo \u00a1Nos esperaban ahora miles de abrazos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Liliana Arrastia<\/strong><br>Rosario, Santa Fe<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"hermandad\">La hermandad<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00f3nica de un encuentro&nbsp; No fue un encuentro. Fueron miles de encuentros. Sucedi\u00f3 ayer. No puedo escribir una cr\u00f3nica del encuentro. Solo puedo escribir la m\u00eda. Que es una entre las doscientas cincuenta que dicen que \u00e9ramos. Mi cr\u00f3nica empieza alrededor de la una del mediod\u00eda cuando llegu\u00e9 al lugar. Entr\u00e9 al Hotel y estaba [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pg-hijes.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11035","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/pages\/11035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/comments?post=11035"}],"version-history":[{"count":23,"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/pages\/11035\/revisions"}],"predecessor-version":[{"id":14157,"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/pages\/11035\/revisions\/14157"}],"wp:attachment":[{"href":"https:\/\/nosotrasenlibertad.com\/libroweb\/wp-json\/wp\/v2\/media?parent=11035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}